{"id":291,"count":1,"description":"","link":"https:\/\/www.canalchat.com\/en\/tag\/crawford\/","name":"Crawford","slug":"crawford","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.canalchat.com\/en\/wp-json\/wp\/v2\/tags\/291"}],"collection":[{"href":"https:\/\/www.canalchat.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.canalchat.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.canalchat.com\/en\/wp-json\/wp\/v2\/posts?tags=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}